{"id":52722,"date":"2022-02-22T09:16:27","date_gmt":"2022-02-22T08:16:27","guid":{"rendered":"https:\/\/biemar.be\/zubehoer-aus-zink\/"},"modified":"2026-03-24T09:49:58","modified_gmt":"2026-03-24T08:49:58","slug":"zubehoer-aus-zink","status":"publish","type":"page","link":"https:\/\/biemar.be\/de\/produkte\/daecher\/zubehoer-aus-zink\/","title":{"rendered":"Zubeh\u00f6r aus Zink"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":51450,"parent":53135,"menu_order":1,"comment_status":"closed","ping_status":"closed","template":"sub-sub-product-page.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-52722","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Zubeh\u00f6r aus Zink | Dach | Biemar Holz<\/title>\n<meta name=\"description\" content=\"Entdecken Sie unser Angebot an Zinkdachzubeh\u00f6r, seine Eigenschaften und die Verf\u00fcgbarkeit in unseren Ausstellungsr\u00e4umen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/biemar.be\/de\/produkte\/daecher\/zubehoer-aus-zink\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Zubeh\u00f6r aus Zink | Dach | Biemar Holz\" \/>\n<meta property=\"og:description\" content=\"Entdecken Sie unser Angebot an Zinkdachzubeh\u00f6r, seine Eigenschaften und die Verf\u00fcgbarkeit in unseren Ausstellungsr\u00e4umen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/biemar.be\/de\/produkte\/daecher\/zubehoer-aus-zink\/\" \/>\n<meta property=\"og:site_name\" content=\"Biemar Bois\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/BiemarBois\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-24T08:49:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/biemar.be\/wp-content\/uploads\/2021\/09\/professional-carpenter-at-work-H86YZHP.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1282\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/biemar.be\\\/de\\\/produkte\\\/daecher\\\/zubehoer-aus-zink\\\/\",\"url\":\"https:\\\/\\\/biemar.be\\\/de\\\/produkte\\\/daecher\\\/zubehoer-aus-zink\\\/\",\"name\":\"Zubeh\u00f6r aus Zink | Dach | Biemar Holz\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/biemar.be\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/biemar.be\\\/de\\\/produkte\\\/daecher\\\/zubehoer-aus-zink\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/biemar.be\\\/de\\\/produkte\\\/daecher\\\/zubehoer-aus-zink\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/biemar.be\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/professional-carpenter-at-work-H86YZHP.jpg\",\"datePublished\":\"2022-02-22T08:16:27+00:00\",\"dateModified\":\"2026-03-24T08:49:58+00:00\",\"description\":\"Entdecken Sie unser Angebot an Zinkdachzubeh\u00f6r, seine Eigenschaften und die Verf\u00fcgbarkeit in unseren Ausstellungsr\u00e4umen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/biemar.be\\\/de\\\/produkte\\\/daecher\\\/zubehoer-aus-zink\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/biemar.be\\\/de\\\/produkte\\\/daecher\\\/zubehoer-aus-zink\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/biemar.be\\\/de\\\/produkte\\\/daecher\\\/zubehoer-aus-zink\\\/#primaryimage\",\"url\":\"https:\\\/\\\/biemar.be\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/professional-carpenter-at-work-H86YZHP.jpg\",\"contentUrl\":\"https:\\\/\\\/biemar.be\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/professional-carpenter-at-work-H86YZHP.jpg\",\"width\":1920,\"height\":1282,\"caption\":\"professional carpenter at work H86YZHP\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/biemar.be\\\/de\\\/produkte\\\/daecher\\\/zubehoer-aus-zink\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Produkte\",\"item\":\"https:\\\/\\\/biemar.be\\\/de\\\/produkte\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"D\u00e4cher\",\"item\":\"https:\\\/\\\/biemar.be\\\/de\\\/produkte\\\/daecher\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Zubeh\u00f6r aus Zink\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/biemar.be\\\/#website\",\"url\":\"https:\\\/\\\/biemar.be\\\/\",\"name\":\"Biemar Bois\",\"description\":\"Des conseils particuli\u00e8rement pro\",\"publisher\":{\"@id\":\"https:\\\/\\\/biemar.be\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/biemar.be\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/biemar.be\\\/#organization\",\"name\":\"Biemar Bois\",\"url\":\"https:\\\/\\\/biemar.be\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/biemar.be\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/biemar.be\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/cropped-fav.jpg\",\"contentUrl\":\"https:\\\/\\\/biemar.be\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/cropped-fav.jpg\",\"width\":512,\"height\":512,\"caption\":\"Biemar Bois\"},\"image\":{\"@id\":\"https:\\\/\\\/biemar.be\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/BiemarBois\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Zubeh\u00f6r aus Zink | Dach | Biemar Holz","description":"Entdecken Sie unser Angebot an Zinkdachzubeh\u00f6r, seine Eigenschaften und die Verf\u00fcgbarkeit in unseren Ausstellungsr\u00e4umen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/biemar.be\/de\/produkte\/daecher\/zubehoer-aus-zink\/","og_locale":"de_DE","og_type":"article","og_title":"Zubeh\u00f6r aus Zink | Dach | Biemar Holz","og_description":"Entdecken Sie unser Angebot an Zinkdachzubeh\u00f6r, seine Eigenschaften und die Verf\u00fcgbarkeit in unseren Ausstellungsr\u00e4umen.","og_url":"https:\/\/biemar.be\/de\/produkte\/daecher\/zubehoer-aus-zink\/","og_site_name":"Biemar Bois","article_publisher":"https:\/\/www.facebook.com\/BiemarBois","article_modified_time":"2026-03-24T08:49:58+00:00","og_image":[{"width":1920,"height":1282,"url":"https:\/\/biemar.be\/wp-content\/uploads\/2021\/09\/professional-carpenter-at-work-H86YZHP.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/biemar.be\/de\/produkte\/daecher\/zubehoer-aus-zink\/","url":"https:\/\/biemar.be\/de\/produkte\/daecher\/zubehoer-aus-zink\/","name":"Zubeh\u00f6r aus Zink | Dach | Biemar Holz","isPartOf":{"@id":"https:\/\/biemar.be\/#website"},"primaryImageOfPage":{"@id":"https:\/\/biemar.be\/de\/produkte\/daecher\/zubehoer-aus-zink\/#primaryimage"},"image":{"@id":"https:\/\/biemar.be\/de\/produkte\/daecher\/zubehoer-aus-zink\/#primaryimage"},"thumbnailUrl":"https:\/\/biemar.be\/wp-content\/uploads\/2021\/09\/professional-carpenter-at-work-H86YZHP.jpg","datePublished":"2022-02-22T08:16:27+00:00","dateModified":"2026-03-24T08:49:58+00:00","description":"Entdecken Sie unser Angebot an Zinkdachzubeh\u00f6r, seine Eigenschaften und die Verf\u00fcgbarkeit in unseren Ausstellungsr\u00e4umen.","breadcrumb":{"@id":"https:\/\/biemar.be\/de\/produkte\/daecher\/zubehoer-aus-zink\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/biemar.be\/de\/produkte\/daecher\/zubehoer-aus-zink\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/biemar.be\/de\/produkte\/daecher\/zubehoer-aus-zink\/#primaryimage","url":"https:\/\/biemar.be\/wp-content\/uploads\/2021\/09\/professional-carpenter-at-work-H86YZHP.jpg","contentUrl":"https:\/\/biemar.be\/wp-content\/uploads\/2021\/09\/professional-carpenter-at-work-H86YZHP.jpg","width":1920,"height":1282,"caption":"professional carpenter at work H86YZHP"},{"@type":"BreadcrumbList","@id":"https:\/\/biemar.be\/de\/produkte\/daecher\/zubehoer-aus-zink\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Produkte","item":"https:\/\/biemar.be\/de\/produkte\/"},{"@type":"ListItem","position":2,"name":"D\u00e4cher","item":"https:\/\/biemar.be\/de\/produkte\/daecher\/"},{"@type":"ListItem","position":3,"name":"Zubeh\u00f6r aus Zink"}]},{"@type":"WebSite","@id":"https:\/\/biemar.be\/#website","url":"https:\/\/biemar.be\/","name":"Biemar Bois","description":"Des conseils particuli\u00e8rement pro","publisher":{"@id":"https:\/\/biemar.be\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/biemar.be\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/biemar.be\/#organization","name":"Biemar Bois","url":"https:\/\/biemar.be\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/biemar.be\/#\/schema\/logo\/image\/","url":"https:\/\/biemar.be\/wp-content\/uploads\/2024\/01\/cropped-fav.jpg","contentUrl":"https:\/\/biemar.be\/wp-content\/uploads\/2024\/01\/cropped-fav.jpg","width":512,"height":512,"caption":"Biemar Bois"},"image":{"@id":"https:\/\/biemar.be\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/BiemarBois"]}]}},"_links":{"self":[{"href":"https:\/\/biemar.be\/de\/wp-json\/wp\/v2\/pages\/52722","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/biemar.be\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/biemar.be\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/biemar.be\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/biemar.be\/de\/wp-json\/wp\/v2\/comments?post=52722"}],"version-history":[{"count":0,"href":"https:\/\/biemar.be\/de\/wp-json\/wp\/v2\/pages\/52722\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/biemar.be\/de\/wp-json\/wp\/v2\/pages\/53135"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/biemar.be\/de\/wp-json\/wp\/v2\/media\/51450"}],"wp:attachment":[{"href":"https:\/\/biemar.be\/de\/wp-json\/wp\/v2\/media?parent=52722"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}